{"id":53248,"date":"2022-12-21T12:27:09","date_gmt":"2022-12-21T11:27:09","guid":{"rendered":"https:\/\/harlander-partner.eu\/proyecto-de-reglamento-de-pistas-poe\/"},"modified":"2025-11-26T04:02:57","modified_gmt":"2025-11-26T03:02:57","slug":"proyecto-de-reglamento-de-pistas-poe","status":"publish","type":"page","link":"https:\/\/harlander-partner.eu\/es\/accidentes-deportivos\/proyecto-de-reglamento-de-pistas-poe\/","title":{"rendered":"Proyecto de reglamento de pistas POE"},"content":{"rendered":"\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2>Proyecto de reglamento de pistas POE <\/h2><ul><li><a href=\"#h-poe-pisten-ordnungs-entwurf\" data-level=\"2\">Proyecto de reglamento de pistas POE<\/a><\/li><li><a href=\"#h-inhalt-des-poe-pisten-ordnungs-entwurfs\" data-level=\"2\">Contenido del proyecto de reglamento de pistas POE<\/a><ul><li><a href=\"#h-1-geltungsbereich\" data-level=\"3\">1. \u00c1mbito de aplicaci\u00f3n<\/a><\/li><li><a href=\"#h-2-skiausrustung\" data-level=\"3\">2. Equipamiento de esqu\u00ed<\/a><\/li><li><a href=\"#h-3-wahl-der-abfahrtstrecke\" data-level=\"3\">3. Elecci\u00f3n de la pista de descenso<\/a><\/li><li><a href=\"#h-4-beobachtungs-und-wartepflicht-des-anfahrenden-oder-in-die-piste-einfahrenden-skifahrers\" data-level=\"3\">4. Obligaci\u00f3n de observaci\u00f3n y espera del esquiador que se aproxima o se incorpora a la pista<\/a><\/li><li><a href=\"#h-5-kontrolliertes-fahren\" data-level=\"3\">5. Conducci\u00f3n controlada<\/a><\/li><li><a href=\"#h-6-fahren-auf-sicht\" data-level=\"3\">6. Conducci\u00f3n con visibilidad<\/a><\/li><li><a href=\"#h-7-notsturz\" data-level=\"3\">7. Ca\u00edda de emergencia<\/a><\/li><li><a href=\"#h-8-vorrang-des-vorderen-langsameren-skifahrers\" data-level=\"3\">8. Prioridad del esquiador delantero m\u00e1s lento<\/a><\/li><li><a href=\"#h-9-sicherheitsabstand\" data-level=\"3\">9. Distancia de seguridad<\/a><\/li><li><a href=\"#h-10-vorrang-des-geschleppten-skifahrers\" data-level=\"3\">10. Prioridad del esquiador remolcado<\/a><\/li><li><a href=\"#h-11-verweilen-auf-der-abfahrtsstrecke\" data-level=\"3\">11. Permanecer en la pista de descenso<\/a><\/li><li><a href=\"#h-12-aufsteigende-skifahrer-und-fussganger\" data-level=\"3\">12. Esquiadores que ascienden y peatones<\/a><\/li><li><a href=\"#h-13-beachtung-der-zeichen\" data-level=\"3\">13. Observaci\u00f3n de las se\u00f1ales<\/a><\/li><li><a href=\"#h-14-pistenbenutzung\" data-level=\"3\">14. Uso de las pistas<\/a><\/li><li><a href=\"#h-15-tiere-auf-pisten\" data-level=\"3\">15. Animales en las pistas<\/a><\/li><li><a href=\"#h-16-verhalten-bei-unfallen\" data-level=\"3\">16. Comportamiento en caso de accidente<\/a><\/li><li><a href=\"#h-17-andere-skipistenbenutzer\" data-level=\"3\">17. Otros usuarios de pistas de esqu\u00ed<\/a><\/li><\/ul><\/li><\/ul><\/div>\n\n<h2 class=\"wp-block-heading\" id=\"h-poe-pisten-ordnungs-entwurf\">Proyecto de reglamento de pistas POE <\/h2>\n\n<p class=\"wp-block-paragraph\">El proyecto de reglamento de pistas POE del Patronato Austriaco para la Seguridad Alpina procede del Patronato Austriaco para la Seguridad Alpina. <\/p>\n\n<div class=\"wp-block-uagb-container uagb-block-3019fe8e alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-45819ab6\"><picture>\r\n\t\t<source srcset=\"https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-352x198.webp\" >\r\n\t\t<img decoding=\"async\" class=\"mr-picture-small\" src=\"https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp\" alt=\"Las normas POE representan un c\u00f3digo de conducta cuyo incumplimiento, en caso de accidente, justifica la culpabilidad.\" >\r\n\t<\/picture>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-32585033\">\n<p class=\"wp-block-paragraph\">Contrariamente a la redacci\u00f3n enga\u00f1osa del punto 1, estas normas de conducta no son una ley.<\/p>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\">Sin embargo, en caso de <a href=\"https:\/\/harlander-partner.eu\/es\/accidentes-deportivos\/abogado-especializado-en-accidentes-de-esqui\/\">accidentes de esqu\u00ed<\/a> y <a href=\"https:\/\/harlander-partner.eu\/es\/accidentes-deportivos\/abogado-especializado-en-accidentes-de-snowboard\/\">accidentes de snowboard<\/a>, los tribunales recurren al proyecto POE, al igual que a las <a href=\"https:\/\/harlander-partner.eu\/es\/accidentes-deportivos\/reglas-fis-para-esquiadores-y-snowboarders\/\">normas FIS<\/a>, como criterio importante para evaluar las obligaciones de diligencia en la pr\u00e1ctica del esqu\u00ed alpino.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-inhalt-des-poe-pisten-ordnungs-entwurfs\">Contenido del proyecto de reglamento de pistas POE<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"h-1-geltungsbereich\">1. \u00c1mbito de aplicaci\u00f3n<\/h3>\n\n<p class=\"wp-block-paragraph\">Esta ley se aplica a las pistas de esqu\u00ed. Como tales, se consideran las pistas de descenso y las laderas de pr\u00e1ctica que son utilizadas de forma general y regular por numerosos esquiadores. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-2-skiausrustung\">2. Equipamiento de esqu\u00ed<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador debe equiparse de tal manera que no ponga en peligro a otros m\u00e1s de lo normal.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-3-wahl-der-abfahrtstrecke\">3. Elecci\u00f3n de la pista de descenso<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador debe tener en cuenta su habilidad al elegir la pista de descenso.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-4-beobachtungs-und-wartepflicht-des-anfahrenden-oder-in-die-piste-einfahrenden-skifahrers\">4. Obligaci\u00f3n de observaci\u00f3n y espera del esquiador que se aproxima o se incorpora a la pista<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador que se aproxima o se incorpora a una pista de esqu\u00ed tiene la obligaci\u00f3n de observar y esperar con respecto a los esquiadores que descienden; tambi\u00e9n debe asegurarse de que puede comenzar o continuar la carrera sin poner en peligro a los que vienen detr\u00e1s.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-5-kontrolliertes-fahren\">5. Conducci\u00f3n controlada<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador debe conducir de forma tan controlada que pueda evitar cualquier obst\u00e1culo o detenerse antes de \u00e9l; en particular, debe adaptar la velocidad a su habilidad, al terreno, a las condiciones de la nieve y a la presencia de otras personas.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-6-fahren-auf-sicht\">6. Conducci\u00f3n con visibilidad<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador debe observar constantemente y con atenci\u00f3n el terreno y a las dem\u00e1s personas que tiene delante durante la marcha,<br \/>tener en cuenta todos los obst\u00e1culos posibles y conducir con visibilidad.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-7-notsturz\">7. Ca\u00edda de emergencia<\/h3>\n\n<p class=\"wp-block-paragraph\">Si el esquiador no puede detenerse o esquivar a tiempo, debe tirarse al suelo para evitar una colisi\u00f3n inminente con otro o para reducir la fuerza del impacto, si esto parece razonable y apropiado para reducir el peligro en las circunstancias dadas.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-8-vorrang-des-vorderen-langsameren-skifahrers\">8. Prioridad del esquiador delantero m\u00e1s lento<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador trasero m\u00e1s r\u00e1pido debe adaptar su forma de conducir al esquiador delantero m\u00e1s lento; este tiene prioridad sobre el conductor trasero. El esquiador no est\u00e1 obligado a observar a los corredores que est\u00e1n detr\u00e1s de \u00e9l durante la marcha, sin embargo, el esquiador que cruza la pista tambi\u00e9n debe observar hacia arriba y tener en cuenta a los corredores que vienen de arriba. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-9-sicherheitsabstand\">9. Distancia de seguridad<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador trasero debe mantener una distancia de seguridad adecuada con respecto al esquiador delantero, el esquiador que adelanta o pasa con respecto a las personas que circulan o est\u00e1n de pie delante de \u00e9l.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-10-vorrang-des-geschleppten-skifahrers\">10. Prioridad del esquiador remolcado<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador remolcado por el telesqu\u00ed tiene prioridad sobre las personas que cruzan el trazado del telesqu\u00ed.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-11-verweilen-auf-der-abfahrtsstrecke\">11. Permanecer en la pista de descenso<\/h3>\n\n<p class=\"wp-block-paragraph\">El esquiador no debe permanecer innecesariamente en un lugar confuso o estrecho de una pista de esqu\u00ed; esto tambi\u00e9n se aplica al esquiador que se ha ca\u00eddo.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-12-aufsteigende-skifahrer-und-fussganger\">12. Esquiadores que ascienden y peatones<\/h3>\n\n<p class=\"wp-block-paragraph\">Los esquiadores que ascienden y los peatones generalmente solo pueden utilizar el borde de una pista de descenso.<br \/><\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-13-beachtung-der-zeichen\">13. Observaci\u00f3n de las se\u00f1ales<\/h3>\n\n<p class=\"wp-block-paragraph\">Todo el mundo debe observar las se\u00f1ales en las pistas de esqu\u00ed.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-14-pistenbenutzung\">14. Uso de las pistas<\/h3>\n\n<p class=\"wp-block-paragraph\">Las pistas de esqu\u00ed solo pueden utilizarse con esqu\u00edes y aquellos equipos de deportes de invierno que no provoquen un peligro especial para otros usuarios.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-15-tiere-auf-pisten\">15. Animales en las pistas<\/h3>\n\n<p class=\"wp-block-paragraph\">Nadie puede dejar que los animales corran libremente por la pista de descenso durante el funcionamiento del esqu\u00ed.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-16-verhalten-bei-unfallen\">16. Comportamiento en caso de accidente<\/h3>\n\n<p class=\"wp-block-paragraph\">Todas las personas implicadas en un accidente de esqu\u00ed deben detenerse, darse a conocer sus nombres y direcciones y prestar a las personas heridas la ayuda necesaria y razonable.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-17-andere-skipistenbenutzer\">17. Otros usuarios de pistas de esqu\u00ed<\/h3>\n\n<p class=\"wp-block-paragraph\">Las disposiciones dictadas para los esquiadores tambi\u00e9n se aplican a los usuarios<br \/>de otros equipos de deportes de invierno en las pistas de esqu\u00ed.<\/p>\n<a class=\"mr-cta-link mr-cta-button-cal\" href=\"#h2-booking\" title=\"Primera consulta gratuita\"><span class=\"mr-cta-link-normal\">Elija ahora su fecha deseada:<\/span><span class=\"mr-cta-link-bold\">Primera consulta gratuita<\/span><\/a>\n","protected":false},"excerpt":{"rendered":"Proyecto de reglamento de pistas POE El proyecto de reglamento de pistas POE del Patronato Austriaco para la Seguridad Alpina procede del Patronato Austriaco para la Seguridad Alpina. Contrariamente a &#8230;","protected":false},"author":1,"featured_media":53251,"parent":58628,"menu_order":93,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[1131],"tags":[],"class_list":["post-53248","page","type-page","status-publish","has-post-thumbnail","hentry","category-derecho-deportivo"],"acf":[],"uagb_featured_image_src":{"full":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp",1920,1080,false],"thumbnail":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-100x100.webp",100,100,true],"medium":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-800x450.webp",800,450,true],"medium_large":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp",1920,1080,false],"large":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp",1920,1080,false],"1536x1536":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp",1536,864,false],"2048x2048":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2.webp",1920,1080,false],"336x":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-336x189.webp",336,189,true],"352x":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-352x198.webp",352,198,true],"woocommerce_thumbnail":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-300x300.webp",300,300,true],"woocommerce_single":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-600x338.webp",600,338,true],"woocommerce_gallery_thumbnail":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-100x100.webp",100,100,true],"yarpp-thumbnail":["https:\/\/harlander-partner.eu\/wp-content\/uploads\/ski-2-120x120.webp",120,120,true]},"uagb_author_info":{"display_name":"Peter Harlander","author_link":"https:\/\/harlander-partner.eu\/es\/author\/secondpromotion\/"},"uagb_comment_info":0,"uagb_excerpt":"Proyecto de reglamento de pistas POE El proyecto de reglamento de pistas POE del Patronato Austriaco para la Seguridad Alpina procede del Patronato Austriaco para la Seguridad Alpina. Contrariamente a ...","_links":{"self":[{"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/pages\/53248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/comments?post=53248"}],"version-history":[{"count":0,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/pages\/53248\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/pages\/58628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/media\/53251"}],"wp:attachment":[{"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/media?parent=53248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/categories?post=53248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/harlander-partner.eu\/es\/wp-json\/wp\/v2\/tags?post=53248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}